{"id":2803,"date":"2025-05-05T09:42:46","date_gmt":"2025-05-05T07:42:46","guid":{"rendered":"https:\/\/myflowin.com\/?p=2803"},"modified":"2025-10-27T12:54:00","modified_gmt":"2025-10-27T11:54:00","slug":"un-guide-rapide-sur-peppol-en-belgique","status":"publish","type":"post","link":"https:\/\/myflowin.com\/fr\/un-guide-rapide-sur-peppol-en-belgique\/","title":{"rendered":"Un guide rapide sur Peppol en Belgique"},"content":{"rendered":"<!--\n    Title: Single Post\n    PostTypes: post\n    SupportsJSX: true\n    UsePostMeta: true\n    Mode: preview\n\n-->\n\n<section class=\"gc-single-post\">\n    <!--\n    Title: Container\n    Mode: preview\n    SupportsJSX: true\n    Blueprint: false\n-->\n\n\n<div class=\"gc-container  gc-single-post__container\">\n    <div class=\"gc-single-post__wrapper\">\n            <div class=\"gc-single-post__date\">5 May 2025<\/div>\n                            <h1 class=\"gc-single-post__title \">Un guide rapide sur Peppol en Belgique<\/h1>\n                    <\/div>\n        <div class=\"gc-single-post__image-wrapper\">\n            <img decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/myflowin.com\/wp-content\/uploads\/image-3.webp\" class=\"gc-single-post__image\" alt=\"\" srcset=\"https:\/\/myflowin.com\/wp-content\/uploads\/image-3.webp 1000w, https:\/\/myflowin.com\/wp-content\/uploads\/image-3-300x180.webp 300w, https:\/\/myflowin.com\/wp-content\/uploads\/image-3-768x461.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>        <\/div>\n        <div class=\"gc-single-post__wrapper\">\n            <div class=\"acf-innerblocks-container\">\n\n<p><\/p>\n\n\n\n<p>Si vos clients font des affaires en Belgique, Peppol est sur le point de devenir un \u00e9l\u00e9ment e de la capacit\u00e9 de leur logiciel \u00e0 envoyer et recevoir des factures. En effet, un mandat \u00e0 venir exigera que toutes les factures \u00e9chang\u00e9es entre entreprises enregistr\u00e9es \u00e0 la TVA en Belgique soient \u00e9mises sous forme de factures \u00e9lectroniques. Dans la plupart des cas, ces factures \u00e9lectroniques devront \u00eatre \u00e9chang\u00e9es via le r\u00e9seau de transmission \u00e9lectronique Peppol. Le mandat belge relatif \u00e0 la facturation \u00e9lectronique entrera en vigueur le 1er&nbsp;janvier 2026.&nbsp;<\/p>\n\n\n\n<p>Peppol n\u2019est ni un syst\u00e8me ni un logiciel \u00e0 acheter pour les entreprises. Il s\u2019agit d\u2019un r\u00e9seau ouvert de transmission \u00e9lectronique auquel les utilisateurs se connectent pour envoyer et recevoir en toute s\u00e9curit\u00e9 des documents \u00e9lectroniques, y compris des factures \u00e9lectroniques. Ces documents doivent se conformer \u00e0 une structure sp\u00e9cifi\u00e9e, et l\u2019acc\u00e8s au r\u00e9seau Peppol est strictement contr\u00f4l\u00e9. Ainsi, bien que Peppol lui-m\u00eame ne soit pas un produit \u00e0 acheter, les ERP et les entreprises doivent s\u2019assurer que leurs syst\u00e8mes ERP peuvent fonctionner avec ce r\u00e9seau.&nbsp;<\/p>\n\n\n\n<p>Nous avons pr\u00e9par\u00e9 un aper\u00e7u simplifi\u00e9 de Peppol pour les entreprises belges, afin de vous aider \u00e0 en comprendre les bases.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/myflowin.com\/fr\/peppol-cest-quoi\/\">En savoir plus : Une br\u00e8ve introduction \u00e0 Peppol<\/a>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Formatage des documents&nbsp;<\/h2>\n\n\n\n<p>Pour que Peppol fonctionne entre chaque utilisateur, les documents transmis via ce r\u00e9seau doivent tous respecter un format standard. Ce format est d\u00e9fini dans les sp\u00e9cifications d\u2019interop\u00e9rabilit\u00e9 commerciale de Peppol (Peppol BIS) et repose sur le langage universel des affaires (Universal Business Language) UBL 2.1, un format XML standardis\u00e9 pour les documents commerciaux.&nbsp;<\/p>\n\n\n\n<p>Le mandat belge relatif \u00e0 la facturation \u00e9lectronique sp\u00e9cifie des formats bas\u00e9s sur la norme europ\u00e9enne EN16931, dont le Peppol BIS Billing 3.0 est le plus couramment utilis\u00e9. Pour plus d\u2019informations, consultez&nbsp;<a href=\"http:\/\/docs.peppol.eu\/poacc\/Billing\/3.0\/\" target=\"_blank\" rel=\"noopener\">http:\/\/docs.peppol.eu\/poacc\/Billing\/3.0\/<\/a>.&nbsp;<\/p>\n\n\n\n<p>Les entreprises utilisant Peppol en Belgique ont la possibilit\u00e9 d\u2019adopter la norme UBL.BE pour les transactions domestiques. Prise en charge par tous les logiciels courants en Belgique, UBL.BE inclut des informations d\u00e9taill\u00e9es sur la TVA ainsi qu\u2019une repr\u00e9sentation visuelle de la facture au format PDF. Cela permet une meilleure automatisation et une facilit\u00e9 d\u2019utilisation accrue. Pour plus d\u2019informations, consultez&nbsp;<a href=\"https:\/\/www.ubl.be\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.UBL.be\/<\/a>.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Identifiants utilisateur Peppol&nbsp;<\/h2>\n\n\n\n<p>Comme tout r\u00e9seau de communication, Peppol doit \u00eatre en mesure d\u2019identifier chaque exp\u00e9diteur et destinataire. Chaque entreprise qui utilise Peppol a donc besoin d\u2019une identit\u00e9 unique, qui doit \u00eatre v\u00e9rifi\u00e9e et enregistr\u00e9e sur le r\u00e9seau Peppol.&nbsp;<\/p>\n\n\n\n<p>Les d\u00e9tails de tous les utilisateurs de Peppol sont stock\u00e9s dans un \u201ccarnet d\u2019adresses\u201d organis\u00e9 en deux niveaux : le SML (Service Metadata Locator) et plusieurs SMPs (Service Metadata Publishers).&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les SMPs contiennent des d\u00e9tails sur le point d\u2019acc\u00e8s Peppol de chaque destinataire (voir ci-dessous \u201cSe connecter \u00e0 Peppol\u201d), ainsi que diverses informations techniques n\u00e9cessaires pour assurer le bon fonctionnement du r\u00e9seau Peppol.\u00a0<\/li>\n\n\n\n<li>Le SML contient tous les num\u00e9ros d\u2019identification des destinataires Peppol, ainsi que l\u2019indication du SMP o\u00f9 se trouvent leurs informations d\u00e9taill\u00e9es.\u00a0<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Se connecter \u00e0 Peppol&nbsp;<\/h2>\n\n\n\n<p>La connexion \u00e0 Peppol s\u2019effectue via un point d\u2019acc\u00e8s Peppol, qui doit \u00eatre maintenu par un fournisseur de point d\u2019acc\u00e8s. Un seul point d\u2019acc\u00e8s Peppol peut desservir de nombreux utilisateurs diff\u00e9rents. La connectivit\u00e9 entre les syst\u00e8mes ERP\/CRM\/comptabilit\u00e9 des entreprises et leur point d\u2019acc\u00e8s Peppol choisi n\u00e9cessite une int\u00e9gration API.&nbsp;<\/p>\n\n\n\n<p>En Belgique, de nombreux logiciels incluent d\u00e9j\u00e0 une int\u00e9gration avec un point d\u2019acc\u00e8s Peppol. Cependant, lorsque ce n\u2019est pas encore le cas, la solution la plus simple pour les \u00e9diteurs de logiciels est de proposer une connexion via une API pr\u00eate \u00e0 l\u2019emploi qui se connecte \u00e0 un point d\u2019acc\u00e8s sp\u00e9cifique.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/myflowin.com\/fr\/options-de-facturation-electronique-b2b-expliquees\/\">En savoir plus : Options d\u2019int\u00e9gration pour la facturation \u00e9lectronique B2B<\/a>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Besoin d\u2019acc\u00e9der \u00e0 Peppol en Belgique ? Flowin vous simplifie la vie !&nbsp;<\/h2>\n\n\n\n<p>Flowin est une API de facturation \u00e9lectronique qui connecte de mani\u00e8re transparente les syst\u00e8mes ERP, CRM et comptabilit\u00e9 au r\u00e9seau Peppol via un point d\u2019acc\u00e8s certifi\u00e9. Avec une mise en \u0153uvre rapide, un support continu complet, et une structure tarifaire particuli\u00e8rement avantageuse, Flowin est la solution la plus simple pour la connectivit\u00e9 Peppol en Belgique.&nbsp;.<\/p>\n\n<\/div>\n        <\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/posts\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/comments?post=2803"}],"version-history":[{"count":1,"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/posts\/2803\/revisions"}],"predecessor-version":[{"id":2804,"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/posts\/2803\/revisions\/2804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/media\/2802"}],"wp:attachment":[{"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/categories?post=2803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myflowin.com\/fr\/wp-json\/wp\/v2\/tags?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}